{"id":25920,"date":"2024-12-28T14:20:11","date_gmt":"2024-12-28T22:20:11","guid":{"rendered":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/"},"modified":"2026-07-08T22:10:52","modified_gmt":"2026-07-09T05:10:52","slug":"seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz","status":"publish","type":"product","link":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/","title":{"rendered":"Seventh Generation Glass Cleaner Spray Sparkling Seaside &#8211; 23oz"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":25536,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[773],"product_tag":[],"class_list":["post-25920","product","type-product","status-publish","has-post-thumbnail","product_cat-detergent-cleaning-pest-control","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Boccato&#039;s Groceries - Sourcing the best wines and culinary treats\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Seventh Generation Glass Cleaner Spray Sparkling Seaside \u2013 23oz - Boccato&#039;s Groceries\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-12-28T22:20:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-09T05:10:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Seventh Generation Glass Cleaner Spray Sparkling Seaside \u2013 23oz - Boccato&#039;s Groceries\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product\\\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/boccatos.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product-category\\\/household-products\\\/#listItem\",\"name\":\"Household Products\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product-category\\\/household-products\\\/#listItem\",\"position\":3,\"name\":\"Household Products\",\"item\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product-category\\\/household-products\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product-category\\\/household-products\\\/detergent-cleaning-pest-control\\\/#listItem\",\"name\":\"Detergent, Cleaning &amp; Pest Control\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product-category\\\/household-products\\\/detergent-cleaning-pest-control\\\/#listItem\",\"position\":4,\"name\":\"Detergent, Cleaning &amp; Pest Control\",\"item\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product-category\\\/household-products\\\/detergent-cleaning-pest-control\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product\\\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\\\/#listItem\",\"name\":\"Seventh Generation Glass Cleaner Spray Sparkling Seaside &#8211; 23oz\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product-category\\\/household-products\\\/#listItem\",\"name\":\"Household Products\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product\\\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\\\/#listItem\",\"position\":5,\"name\":\"Seventh Generation Glass Cleaner Spray Sparkling Seaside &#8211; 23oz\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product-category\\\/household-products\\\/detergent-cleaning-pest-control\\\/#listItem\",\"name\":\"Detergent, Cleaning &amp; Pest Control\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product\\\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\\\/#itempage\",\"url\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product\\\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\\\/\",\"name\":\"Seventh Generation Glass Cleaner Spray Sparkling Seaside \\u2013 23oz - Boccato's Groceries\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boccatos.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product\\\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/boccatos.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/732913447121.jpg?fit=1752%2C1752&ssl=1\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product\\\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\\\/#mainImage\",\"width\":1752,\"height\":1752},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boccatos.com\\\/index.php\\\/product\\\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\\\/#mainImage\"},\"datePublished\":\"2024-12-28T14:20:11-08:00\",\"dateModified\":\"2026-07-08T22:10:52-07:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/#organization\",\"name\":\"Boccato's Groceries\",\"description\":\"Sourcing the best wines and culinary treats\",\"url\":\"https:\\\/\\\/boccatos.com\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boccatos.com\\\/#website\",\"url\":\"https:\\\/\\\/boccatos.com\\\/\",\"name\":\"Boccatos.com\",\"description\":\"Sourcing the best wines and culinary treats\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/boccatos.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Seventh Generation Glass Cleaner Spray Sparkling Seaside \u2013 23oz - Boccato's Groceries","description":"","canonical_url":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/boccatos.com#listItem","position":1,"name":"Home","item":"https:\/\/boccatos.com","nextItem":{"@type":"ListItem","@id":"https:\/\/boccatos.com\/index.php\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/boccatos.com\/index.php\/shop\/#listItem","position":2,"name":"Shop","item":"https:\/\/boccatos.com\/index.php\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/#listItem","name":"Household Products"},"previousItem":{"@type":"ListItem","@id":"https:\/\/boccatos.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/#listItem","position":3,"name":"Household Products","item":"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/","nextItem":{"@type":"ListItem","@id":"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/detergent-cleaning-pest-control\/#listItem","name":"Detergent, Cleaning &amp; Pest Control"},"previousItem":{"@type":"ListItem","@id":"https:\/\/boccatos.com\/index.php\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/detergent-cleaning-pest-control\/#listItem","position":4,"name":"Detergent, Cleaning &amp; Pest Control","item":"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/detergent-cleaning-pest-control\/","nextItem":{"@type":"ListItem","@id":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/#listItem","name":"Seventh Generation Glass Cleaner Spray Sparkling Seaside &#8211; 23oz"},"previousItem":{"@type":"ListItem","@id":"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/#listItem","name":"Household Products"}},{"@type":"ListItem","@id":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/#listItem","position":5,"name":"Seventh Generation Glass Cleaner Spray Sparkling Seaside &#8211; 23oz","previousItem":{"@type":"ListItem","@id":"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/detergent-cleaning-pest-control\/#listItem","name":"Detergent, Cleaning &amp; Pest Control"}}]},{"@type":"ItemPage","@id":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/#itempage","url":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/","name":"Seventh Generation Glass Cleaner Spray Sparkling Seaside \u2013 23oz - Boccato's Groceries","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/boccatos.com\/#website"},"breadcrumb":{"@id":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/boccatos.com\/wp-content\/uploads\/2024\/12\/732913447121.jpg?fit=1752%2C1752&ssl=1","@id":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/#mainImage","width":1752,"height":1752},"primaryImageOfPage":{"@id":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/#mainImage"},"datePublished":"2024-12-28T14:20:11-08:00","dateModified":"2026-07-08T22:10:52-07:00"},{"@type":"Organization","@id":"https:\/\/boccatos.com\/#organization","name":"Boccato's Groceries","description":"Sourcing the best wines and culinary treats","url":"https:\/\/boccatos.com\/"},{"@type":"WebSite","@id":"https:\/\/boccatos.com\/#website","url":"https:\/\/boccatos.com\/","name":"Boccatos.com","description":"Sourcing the best wines and culinary treats","inLanguage":"en-US","publisher":{"@id":"https:\/\/boccatos.com\/#organization"}}]},"og:locale":"en_US","og:site_name":"Boccato's Groceries - Sourcing the best wines and culinary treats","og:type":"article","og:title":"Seventh Generation Glass Cleaner Spray Sparkling Seaside \u2013 23oz - Boccato's Groceries","og:url":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/","article:published_time":"2024-12-28T22:20:11+00:00","article:modified_time":"2026-07-09T05:10:52+00:00","twitter:card":"summary","twitter:title":"Seventh Generation Glass Cleaner Spray Sparkling Seaside \u2013 23oz - Boccato's Groceries"},"aioseo_meta_data":{"post_id":"25920","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-12-29 17:19:58","updated":"2026-07-09 14:00:56","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/boccatos.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/boccatos.com\/index.php\/shop\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/\" title=\"Household Products\">Household Products<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/detergent-cleaning-pest-control\/\" title=\"Detergent, Cleaning &amp; Pest Control\">Detergent, Cleaning &amp; Pest Control<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSeventh Generation Glass Cleaner Spray Sparkling Seaside \u2013 23oz\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/boccatos.com"},{"label":"Shop","link":"https:\/\/boccatos.com\/index.php\/shop\/"},{"label":"Household Products","link":"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/"},{"label":"Detergent, Cleaning &amp; Pest Control","link":"https:\/\/boccatos.com\/index.php\/product-category\/household-products\/detergent-cleaning-pest-control\/"},{"label":"Seventh Generation Glass Cleaner Spray Sparkling Seaside &#8211; 23oz","link":"https:\/\/boccatos.com\/index.php\/product\/seventh-generation-glass-cleaner-spray-sparkling-seaside-23oz\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/boccatos.com\/index.php\/wp-json\/wp\/v2\/product\/25920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boccatos.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/boccatos.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boccatos.com\/index.php\/wp-json\/wp\/v2\/media\/25536"}],"wp:attachment":[{"href":"https:\/\/boccatos.com\/index.php\/wp-json\/wp\/v2\/media?parent=25920"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/boccatos.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=25920"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/boccatos.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=25920"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/boccatos.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=25920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}